{"id":5669,"date":"2019-10-18T13:45:28","date_gmt":"2019-10-18T12:45:28","guid":{"rendered":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/?p=5669"},"modified":"2020-01-17T00:13:11","modified_gmt":"2020-01-16T23:13:11","slug":"stellenauschreibung","status":"publish","type":"post","link":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/2019\/10\/stellenauschreibung\/","title":{"rendered":"Stellenauschreibung Sozialarbeiter*innen f\u00fcr Soziale Arbeit in Kitas"},"content":{"rendered":"\n<h6>Magdeburg. 18.10.2019<\/h6>\n<p>Das Landesjugendwerk der AWO Sachsen-Anhalt e.V. ist der unabh\u00e4ngige Kinder- und Jugendverband der Arbeiterwohlfahrt in Sachsen-Anhalt, landesweit anerkannter Tr\u00e4ger der freien Jugendhilfe nach \u00a7 75 KJHG sowie Tr\u00e4ger von Schulsozialarbeit, offener Jugendarbeit, des Freiwilligen Sozialen Jahres (FSJ) und des Bundesfreiwilligendienstes (BFD) in Sachsen-Anhalt. In der au\u00dferschulischen Jugendbildung werden von uns Seminare, Workshops und Gedenkst\u00e4ttenfahrten fu\u0308r Jugendliche und junge Erwachsene bis 27 Jahre sowie fu\u0308r ehrenamtliche Mitarbeiter*innen der Kinder- und Jugendarbeit organisiert und durchgefu\u0308hrt.<br \/>Wir sind politisch und konfessionell unabh\u00e4ngig. Bei uns engagieren sich junge Menschen fu\u0308r junge Menschen. Als landesweit agierender Jugendverband treten wir fu\u0308r eine tolerante, offene und gerechte Gesellschaft ein und engagieren uns als politische Interessenvertretung von Kindern und Jugendlichen fu\u0308r deren st\u00e4rkere Beteiligung in allen Lebensbereichen. Unsere Grundwerte Solidarit\u00e4t, Freiheit, Gerechtigkeit, Gleichheit, Emanzipation und Toleranz sind dabei Grundlage unseres Handelns.<\/p>\n<p>Ein Arbeitsfeld des Landesjugendwerkes der AWO ist Soziale Arbeit in Kitas. Dabei sollen Sozialarbeiter*innen zur Herstellung von Chancengerechtigkeit und zum Ausgleich individueller Benachteiligungen von Kindern durch besondere F\u00f6rderung beitragen und so vor allem eine positive Bildungsbiografie aller Kinder bef\u00f6rdern. Ziele der F\u00f6rderung sind insbesondere die St\u00e4rkung der Resilienz der Kinder, die allgemeine Gesundheitsf\u00f6rderung, die St\u00e4rkung der sprachlichen und inklusiven Bildung, der Ausgleich von Bildungsbenachteiligungen, die St\u00e4rkung der Kinderbeteiligung, die St\u00e4rkung der Einrichtung in der Zusammenarbeit mit den Eltern, die St\u00e4rkung der Team- und Netzwerkarbeit und die St\u00e4rkung der Fachlichkeit der Einrichtung im Umgang mit Heterogenit\u00e4t und Interkulturalit\u00e4t.<br \/><br \/>Zur Umsetzung dieser Aufgaben an mehreren Magdeburger Kitas suchen wir zum 01.01.2020 mehrere<br \/><br \/><strong>Sozialarbeiter*innen<\/strong><br \/><br \/>Die Stellen umfassen jeweils eine Wochenarbeitszeit von 20, 30 oder 40 Stunden und sind zun\u00e4chst bis zum 31.12.2024 befristet, eine Verl\u00e4ngerung wird angestrebt.<\/p>\n<p><strong>Aufgaben:<\/strong><\/p>\n<ul>\n<li>Verringerung von Problemlagen, Belastungen und Benachteiligungen<\/li>\n<li>Ermittlung konkreter Bedarfe der Kinder<\/li>\n<li>Beratungen zu verschiedenen Themen rund um das Kind<\/li>\n<li>Integrationsarbeit<\/li>\n<li>Beratung und Unterstu\u0308tzung bei Antragstellungen, z.B. zur Sicherung der Inanspruchnahme finanzieller Hilfen aus dem Bildungs- und Teilhabepaket<\/li>\n<li>Bedarfsbezogene Projektarbeit und Gruppenarbeit<\/li>\n<li>Vermittlung von Unterstu\u0308tzungs- und Hilfsangeboten, Wegweiserberatung an Fachstellen<\/li>\n<li>Begleitungs- und Hilfsangebote zur Unterstu\u0308tzung der Gesundheitsf\u00f6rderung des Kindes sowie der sprachlichen und inklusiven Bildung<\/li>\n<li>Unterstu\u0308tzung, Beratung, Begleitung und Soforthilfe in Krisensituationen<\/li>\n<li>Eltern- und Familienarbeit<\/li>\n<li>Kooperation mit der Grundschul-Sozialarbeit<\/li>\n<li>Fachaustausch mit Leitung und p\u00e4dagogischem Personal<\/li>\n<li>Unterstu\u0308tzung und Beratung der Fachkr\u00e4fte bei besonderen Herausforderungen<\/li>\n<li>Vorbereitung und Unterstu\u0308tzung bei schwierigen Elterngespr\u00e4chen<\/li>\n<li>Gemeinwesen- und Netzwerkarbeit sowie \u00d6ffentlichkeitsarbeit<\/li>\n<li>Zusammenarbeit mit Institutionen und interdisziplin\u00e4re Zusammenarbeit<\/li>\n<li>Verwaltung, Dokumentation und Evaluation des Projektes<\/li>\n<li>Teilnahme an Fortbildungen und Fachtagungen<\/li>\n<\/ul>\n<p><strong>Erwartungen:<\/strong><\/p>\n<ul>\n<li>abgeschlossenes Hochschulstudium (Uni\/FH) vorzugsweise in Sozialarbeit\/Sozialp\u00e4dagogik (Diplom\/BA\/MA), Erziehungswissenschaften, Sozial- und Bildungswissenschaften bzw. vergleichbaren Abschluss mit p\u00e4dagogischen Inhalten<\/li>\n<li>Vertrautheit mit den Strukturen und Inhalten der Bildungs- oder Beratungsarbeit an Kitas, Einzelfallhilfe und Gruppenarbeit sowie mit Partizipationsprozessen<\/li>\n<li>F\u00e4higkeit zum wertsch\u00e4tzenden Umgang<\/li>\n<li>sicheres Auftreten, Teamf\u00e4higkeit, Kontaktfreude, Organisations- und<br \/>Kommunikationsgeschick<\/li>\n<li>Einsatzbereitschaft, Flexibilit\u00e4t, Bereitschaft zur Innovation<\/li>\n<li>Erfahrungen in der \u00d6ffentlichkeitsarbeit, Netzwerkarbeit und Interessensvertretung<\/li>\n<li>Belastbarkeit und Reflexionsf\u00e4higkeit<\/li>\n<\/ul>\n<p><strong>Wir bieten:<\/strong><\/p>\n<ul>\n<li>eine interessante und vielseitige T\u00e4tigkeit in einem landesweit agierenden Jugendverband<\/li>\n<li>einen engagierten, jungen Vorstand und ein motiviertes Team in verschiedenen Arbeitsbereichen<\/li>\n<li>vielf\u00e4ltige Lern- und Fortbildungsfelder<\/li>\n<li>die M\u00f6glichkeit, das ausgeschriebene Arbeitsfeld und die Arbeit des Landesjugendwerkes der AWO aktiv mitzugestalten<\/li>\n<li>eine leistungsgerechte Vergu\u0308tung in Anlehnung an TV\u00d6D S12<\/li>\n<\/ul>\n<p><strong>Bewerbung:<\/strong><\/p>\n<p>Ihre aussagekr\u00e4ftige Bewerbung richten Sie bitte bis zum 10.11.2019 \u2013 per E-Mail mit EINER PDF-Datei als Anhang mit max. 5 MB &#8211; an:<br \/><br \/>Landesjugendwerk der AWO Sachsen-Anhalt e.V.<br \/>Tom Bruchholz, Gesch\u00e4ftsfu\u0308hrer<br \/>Sch\u00f6nebecker Stra\u00dfe 82-84<br \/>39104 Magdeburg<br \/>Telefon: 0391-83 80 90 44 <br \/>E-Mail: <a href=\"mailto:Bildung@AWO-Jugendwerk-LSA.de\">Bildung@AWO-Jugendwerk-LSA.de<\/a><br \/><br \/>Die Bewerbungsgespr\u00e4che finden am 14.11.2019 in Magdeburg statt.<br \/>Fu\u0308r Ru\u0308ckfragen stehen wir Ihnen gern zur Verfu\u0308gung. <br \/><br \/>Wir freuen uns auf Ihre Bewerbung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magdeburg. 18.10.2019 Das Landesjugendwerk der AWO Sachsen-Anhalt e.V. ist der unabh\u00e4ngige Kinder- und Jugendverband der Arbeiterwohlfahrt in Sachsen-Anhalt, landesweit anerkannter Tr\u00e4ger der freien Jugendhilfe nach \u00a7 75 KJHG sowie Tr\u00e4ger von Schulsozialarbeit, offener Jugendarbeit, des Freiwilligen Sozialen Jahres (FSJ) und des Bundesfreiwilligendienstes (BFD) in Sachsen-Anhalt. In der au\u00dferschulischen Jugendbildung werden von uns Seminare, Workshops und <a class=\"more-link\" href=\"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/2019\/10\/stellenauschreibung\/\">weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5669","post","type-post","status-publish","format-standard","hentry","category-events"],"_links":{"self":[{"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/posts\/5669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/comments?post=5669"}],"version-history":[{"count":5,"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/posts\/5669\/revisions"}],"predecessor-version":[{"id":5744,"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/posts\/5669\/revisions\/5744"}],"wp:attachment":[{"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/media?parent=5669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/categories?post=5669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.awo-jugendwerk-lsa.de\/awowp\/wp-json\/wp\/v2\/tags?post=5669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}